{"id":5423,"date":"2025-09-10T21:54:12","date_gmt":"2025-09-10T13:54:12","guid":{"rendered":"https:\/\/www.jodoo.com\/blog\/?p=5423"},"modified":"2025-09-11T16:21:58","modified_gmt":"2025-09-11T08:21:58","slug":"kundengeschichte-lizheng","status":"publish","type":"post","link":"https:\/\/www.jodoo.com\/blog\/de-de\/customer-story-lizheng","title":{"rendered":"Revolutionierung des Baumanagements: Die digitale Transformation von Li Zheng Decoration mit Jodoo"},"content":{"rendered":"<div class=\"wp-block-stackable-feature-grid stk-block-feature-grid stk-block-columns stk-block stk-fa9aa32 is-style-default no-toc\" data-block-id=\"fa9aa32\"><style>.stk-fa9aa32 {margin-bottom:32px !important;}.stk-fa9aa32-column{--stk-column-gap:20px !important;}<\/style><div class=\"stk-row stk-inner-blocks has-text-align-center stk-block-content stk-content-align stk-fa9aa32-column\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-024a12d stk-block-background\" data-v=\"4\" data-block-id=\"024a12d\"><style>.stk-024a12d-container{margin-top:0px !important;margin-right:0px !important;margin-bottom:0px !important;margin-left:0px !important;background-color:var(--theme-palette-color-16, #E7F0EE) !important;box-shadow:none !important;padding-top:20px !important;padding-right:20px !important;padding-bottom:20px !important;padding-left:20px !important;}.stk-024a12d {background-color:var(--theme-palette-color-16, #E7F0EE) !important;border-top-left-radius:8px !important;border-top-right-radius:8px !important;border-bottom-right-radius:8px !important;border-bottom-left-radius:8px !important;overflow:hidden !important;box-shadow:-4px 4px 0px 0px var(--theme-palette-color-10, #136A50) !important;border-style:solid !important;border-color:var(--theme-palette-color-10, #136A50) !important;border-top-width:2px !important;border-right-width:2px !important;border-bottom-width:2px !important;border-left-width:2px !important;padding-top:0px !important;padding-right:0px !important;padding-bottom:0px !important;padding-left:0px !important;}.stk-024a12d:before{background-color:var(--theme-palette-color-16, #E7F0EE) !important;}.stk-024a12d-container:before{background-color:var(--theme-palette-color-16, #E7F0EE) !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-024a12d-container stk-hover-parent\"><div class=\"stk-block-content stk-inner-blocks stk-024a12d-inner-blocks\">\n<p class=\"has-text-align-left has-large-font-size\" style=\"margin-top:0;margin-bottom:0;padding-top:0;padding-right:0;padding-bottom:0;padding-left:0\"><strong><span style=\"color: var(--theme-palette-color-10, #136A50);\" class=\"stk-highlight\">90%<\/span><\/strong><\/p>\n\n\n\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-7b966f2\" data-block-id=\"7b966f2\"><p class=\"stk-block-text__text has-text-align-left\">Verbesserte Effizienz des Online-B\u00fcros<\/p><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-bf4637c stk-block-background\" data-v=\"4\" data-block-id=\"bf4637c\"><style>.stk-bf4637c-container{margin-top:0px !important;margin-right:0px !important;margin-bottom:0px !important;margin-left:0px !important;background-color:var(--theme-palette-color-16, #E7F0EE) !important;padding-top:20px !important;padding-right:20px !important;padding-bottom:20px !important;padding-left:20px !important;}.stk-bf4637c {background-color:var(--theme-palette-color-16, #E7F0EE) !important;border-top-left-radius:8px !important;border-top-right-radius:8px !important;border-bottom-right-radius:8px !important;border-bottom-left-radius:8px !important;overflow:hidden !important;box-shadow:-4px 4px 0px 0px var(--theme-palette-color-10, #136A50) !important;border-style:solid !important;border-color:var(--theme-palette-color-10, #136A50) !important;border-top-width:2px !important;border-right-width:2px !important;border-bottom-width:2px !important;border-left-width:2px !important;padding-top:0px !important;padding-right:0px !important;padding-bottom:0px !important;padding-left:0px !important;}.stk-bf4637c:before{background-color:var(--theme-palette-color-16, #E7F0EE) !important;}.stk-bf4637c-container:before{background-color:var(--theme-palette-color-16, #E7F0EE) !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-bf4637c-container stk-hover-parent\"><div class=\"stk-block-content stk-inner-blocks stk-bf4637c-inner-blocks\">\n<p class=\"has-text-align-left has-palette-color-10-color has-text-color has-link-color has-large-font-size wp-elements-82a8809b76d63c4b76947293fcea1435\" style=\"margin-top:0;margin-bottom:0\"><strong>80%<\/strong><\/p>\n\n\n\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-66968b8\" data-block-id=\"66968b8\"><p class=\"stk-block-text__text has-text-align-left\">Zeitersparnis bei der Datenerfassung und -sortierung<\/p><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-5efe5d4 stk-block-background\" data-v=\"4\" data-block-id=\"5efe5d4\"><style>.stk-5efe5d4-container{margin-top:0px !important;margin-right:0px !important;margin-bottom:0px !important;margin-left:0px !important;background-color:var(--theme-palette-color-16, #E7F0EE) !important;padding-top:20px !important;padding-right:20px !important;padding-bottom:20px !important;padding-left:20px !important;}.stk-5efe5d4 {background-color:var(--theme-palette-color-16, #E7F0EE) !important;border-top-left-radius:8px !important;border-top-right-radius:8px !important;border-bottom-right-radius:8px !important;border-bottom-left-radius:8px !important;overflow:hidden !important;box-shadow:-4px 4px 0px 0px var(--theme-palette-color-10, #136A50) !important;border-style:solid !important;border-color:var(--theme-palette-color-10, #136A50) !important;border-top-width:2px !important;border-right-width:2px !important;border-bottom-width:2px !important;border-left-width:2px !important;padding-top:0px !important;padding-right:0px !important;padding-bottom:0px !important;padding-left:0px !important;}.stk-5efe5d4:before{background-color:var(--theme-palette-color-16, #E7F0EE) !important;}.stk-5efe5d4-container:before{background-color:var(--theme-palette-color-16, #E7F0EE) !important;}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-5efe5d4-container stk-hover-parent\"><div class=\"stk-block-content stk-inner-blocks stk-5efe5d4-inner-blocks\">\n<p class=\"has-text-align-left has-large-font-size\" style=\"margin-top:0;margin-bottom:0\"><strong><span style=\"color: var(--theme-palette-color-10, #136A50);\" class=\"stk-highlight\">80%<\/span><\/strong><\/p>\n\n\n\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-d8bcaf2\" data-block-id=\"d8bcaf2\"><p class=\"stk-block-text__text has-text-align-left\">Verbesserte datengest\u00fctzte Entscheidungsfindung<\/p><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<blockquote class=\"wp-block-stackable-blockquote stk-block-blockquote stk-block stk-d071100 is-style-default\" data-v=\"2\" data-block-id=\"d071100\"><style>.stk-d071100-container{background-color:var(--theme-palette-color-6, #f2f5f7) !important;border-top-left-radius:4px !important;border-top-right-radius:4px !important;border-bottom-right-radius:4px !important;border-bottom-left-radius:4px !important;overflow:hidden !important;box-shadow:none !important;}.stk-d071100-container:before{background-color:var(--theme-palette-color-6, #f2f5f7) !important;}<\/style><div class=\"has-text-align-left stk-block-blockquote__content stk-container stk-d071100-container stk-hover-parent\"><div class=\"stk-block-content stk-inner-blocks\">\n<div class=\"wp-block-stackable-icon stk-block-icon stk-block stk-42c34b4\" data-block-id=\"42c34b4\"><span class=\"stk--svg-wrapper\"><div class=\"stk--inner-svg\"><svg style=\"height:0;width:0\"><defs><lineargradient id=\"linear-gradient-42c34b4\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\"><stop offset=\"0%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-42-c-34-b-4-color-1)\"><\/stop><stop offset=\"100%\" style=\"stop-opacity:1;stop-color:var(--linear-gradient-42-c-34-b-4-color-2)\"><\/stop><\/lineargradient><\/defs><\/svg><svg class=\"ugb-custom-icon\" viewbox=\"0 0 32 33\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" width=\"32\" height=\"32\">\n<path d=\"M6.111 23.913C4.7374 22.4548 3.9998 20.8182 3.9998 18.1653C3.9998 13.4994 7.27513 9.31646 12.0406 7.24913L13.2309 9.08593C8.7838 11.4921 7.91473 14.613 7.56726 16.5809C8.28326 16.2106 9.2206 16.0805 10.1394 16.1655C12.5453 16.3886 14.4414 18.3637 14.4414 20.8182C14.4414 23.3955 12.3521 25.4849 9.77473 25.4849C8.34393 25.4849 6.9758 24.8309 6.111 23.913ZM19.4443 23.913C18.0707 22.4548 17.3331 20.8182 17.3331 18.1653C17.3331 13.4994 20.6085 9.31646 25.3739 7.24913L26.5642 9.08593C22.1172 11.4921 21.248 14.613 20.9006 16.5809C21.6166 16.2106 22.5539 16.0805 23.4727 16.1655C25.8786 16.3886 27.7747 18.3637 27.7747 20.8182C27.7747 23.3955 25.6853 25.4849 23.108 25.4849C21.6773 25.4849 20.3091 24.8309 19.4443 23.913Z\" fill=\"#BEBEBE\"><\/path>\n<\/svg><\/div><\/span><\/div>\n\n\n\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-92b72b6\" data-block-id=\"92b72b6\"><style>.stk-92b72b6 .stk-block-text__text{font-style:italic !important;}<\/style><p class=\"stk-block-text__text\">Durch den Einsatz von Jodoo konnte die Effizienz des Online-B\u00fcros von Li Zheng Decoration im Vergleich zum vorherigen Websystem um 901.030 Tsd. gesteigert werden. W\u00f6chentlich werden dadurch 801.030 Tsd. Zeit bei der Organisation und Erfassung verschiedener Unternehmensdaten eingespart. Die Gesch\u00e4ftsleitung verf\u00fcgt nun \u00fcber fundierte Daten zur Analyse der Gesch\u00e4ftst\u00e4tigkeit von Li Zheng Construction und kann so ein zeitnahes und effizientes umfassendes Betriebsmanagement gew\u00e4hrleisten.<br><span style=\"color: var(--theme-palette-color-17, #666666);\" class=\"stk-highlight\">\u2014 Li Zheng Decoration Engineering Co., Ltd.<\/span><\/p><\/div>\n<\/div><\/div><\/blockquote>\n\n\n\n<p>In der dynamischen und oft komplexen Bauwelt sind Effizienz, Pr\u00e4zision und Anpassungsf\u00e4higkeit von gr\u00f6\u00dfter Bedeutung. Die Li Zheng Decoration Engineering Co., Ltd., ein renommiertes mittelst\u00e4ndisches Unternehmen im Bereich Innenausbau, stand vor \u00e4hnlichen Herausforderungen wie viele andere Unternehmen der Baubranche. Spezialisiert auf hochwertige Innenausbauten f\u00fcr Wohn- und Gewerbeimmobilien, betreut Li Zheng Decoration einen vielf\u00e4ltigen Kundenstamm, darunter die 50 gr\u00f6\u00dften Immobilienunternehmen des Landes, und besch\u00e4ftigt \u00fcber 70 Mitarbeiter, die j\u00e4hrlich mehr als 400 Bauarbeiter unterst\u00fctzen. Trotz seiner schlanken und effizienten internen Managementstruktur erkannte das Unternehmen die Notwendigkeit einer digitalen Transformation, um operative Engp\u00e4sse zu beseitigen und neue Produktivit\u00e4ts- und strategische Erkenntnisse zu gewinnen.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter has-custom-border\"><img decoding=\"async\" src=\"https:\/\/t9018308706.p.clickup-attachments.com\/t9018308706\/1ba4ae18-1d1d-47e0-bc7e-f4f45cceb4cf\/office-730681_1280.jpg\" alt=\"\" style=\"border-radius:8px\"\/><\/figure>\n\n\n\n<p>Diese Kundengeschichte zeigt, wie Li Zheng Decoration die No-Code-Plattform von Jodoo nutzte, um seine Baumanagementprozesse grundlegend zu ver\u00e4ndern und kritische Schwachstellen in den Bereichen Mitarbeitermanagement, Kostenkontrolle und Lieferkettenmanagement zu beheben. Durch die Digitalisierung optimierte Li Zheng Decoration nicht nur seine t\u00e4glichen Abl\u00e4ufe, sondern legte auch ein solides Fundament f\u00fcr zuk\u00fcnftiges Wachstum und datengest\u00fctzte Entscheidungen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"challenges-faced\"><\/span>Herausforderungen<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<figure class=\"wp-block-image aligncenter has-custom-border\"><img decoding=\"async\" src=\"https:\/\/t9018308706.p.clickup-attachments.com\/t9018308706\/d3e443ce-d444-472a-9f9a-cf07f84f2d8f\/image.png\" alt=\"\" style=\"border-radius:8px\"\/><\/figure>\n\n\n\n<p>Vor der Einf\u00fchrung von Jodoo hatte Li Zheng Decoration mit mehreren betrieblichen Ineffizienzen zu k\u00e4mpfen, die das Wachstum und die Agilit\u00e4t des Unternehmens behinderten:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"outdated-and-inflexible-system-processes\"><\/span>Veraltete und unflexible Systemprozesse<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Die urspr\u00fcnglichen Systemprozesse des Unternehmens waren unflexibel und nicht automatisiert. Kritische Arbeitsabl\u00e4ufe liefen oft ohne rechtzeitige Erinnerungen ab, und jede Anmeldung \u00fcber den Webbrowser erforderte m\u00fchsame und komplexe Konfigurationen. Dieser manuelle Aufwand kostete wertvolle Zeit, barg das Risiko menschlicher Fehler und verlangsamte den gesamten Betrieb.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"inefficient-worker-management-and-data-collection\"><\/span>Ineffizientes Mitarbeitermanagement und Datenerfassung<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Die Verwaltung einer gro\u00dfen Belegschaft, insbesondere im dynamischen Bauumfeld, stellte erhebliche Herausforderungen dar. Die Einarbeitung der Mitarbeiter erfolgte zun\u00e4chst papierbasiert und umfasste drei Schulungsstufen, wobei alle Identit\u00e4ts- und Bankkarteninformationen manuell erfasst wurden. Diese manuelle Dateneingabe f\u00fchrte h\u00e4ufig zu Fehlern, wie beispielsweise falschen oder fehlenden Zahlen und falsch geschriebenen Namen in den Gehaltstabellen. Dies verursachte Verz\u00f6gerungen und einen erheblichen Aufwand bei der Abstimmung w\u00e4hrend der Zahlungszyklen. Dar\u00fcber hinaus wiesen die herk\u00f6mmlichen Zeiterfassungsmethoden \u2013 von Lochkarten \u00fcber Gesichtserkennung und Fingerabdruckscanner bis hin zu Zutrittskontrollsystemen \u2013 Sicherheitsl\u00fccken auf. Probleme wie das Ein- und Ausstempeln durch Dritte, nicht erkannte biometrische Daten, Stromausf\u00e4lle, die die Zeiterfassungsger\u00e4te beeintr\u00e4chtigten, oder Diebstahlrisiken an festen Standorten machten eine Echtzeit\u00fcberwachung unm\u00f6glich. Administratoren konnten nur \u00fcber USB-Sticks auf die Anwesenheitsdaten zugreifen, was eine sofortige Kontrolle und ein rechtzeitiges Eingreifen verhinderte.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"suboptimal-cost-control-and-project-management\"><\/span>Suboptimale Kostenkontrolle und Projektmanagement<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Die Bearbeitung der \u00c4nderungsantr\u00e4ge von Vertragspartner A stellte ein erhebliches Problem f\u00fcr die Kostenkontrolle im Bauprojekt dar. Verz\u00f6gerungen bei der Bearbeitung, die versp\u00e4tete Archivierung von Baufotos und Datenverluste aufgrund von Personalwechseln waren h\u00e4ufig. Fehlende Echtzeit-Verfolgung und Erinnerungen versch\u00e4rften diese Probleme zus\u00e4tzlich und f\u00fchrten zu verz\u00f6gerten Projektabrechnungen und einer langsameren Kapitalr\u00fcckgewinnung. Auch dem Finanzmanagement fehlte ein umfassendes System zur Planung und Zuweisung von Projektmitteln, und Aktualisierungen des Materialbestands erfolgten oft nicht zeitnah, was sich negativ auf Projektzeitpl\u00e4ne und Budgets auswirkte.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"jodoos-solution-a-comprehensive-digital-transformation\"><\/span>Die L\u00f6sung von Jodoo: Eine umfassende digitale Transformation<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<figure class=\"wp-block-image aligncenter has-custom-border\"><img decoding=\"async\" src=\"https:\/\/t9018308706.p.clickup-attachments.com\/t9018308706\/5a3f19a6-8d0f-429f-ab0e-2ccf762a2545\/image.png\" alt=\"\" style=\"border-radius:8px\"\/><\/figure>\n\n\n\n<p>Li Zheng Decoration hat in Zusammenarbeit mit Jodoo eine umfassende digitale L\u00f6sung implementiert, die die zentralen operativen Herausforderungen des Unternehmens adressiert. Mithilfe der flexiblen und leistungsstarken No-Code-Plattform von Jodoo entwickelte das Unternehmen eine Reihe von Anwendungen, die auf seine spezifischen Bed\u00fcrfnisse zugeschnitten sind und sich auf Mitarbeitermanagement, Kostenkontrolle und Optimierung der Lieferkette konzentrieren.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"scenario-1-building-a-robust-worker-information-database-and-attendance-system\"><\/span>Szenario 1: Aufbau einer robusten Mitarbeiterinformationsdatenbank und eines Anwesenheitssystems<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Um die Einschr\u00e4nkungen des traditionellen Mitarbeitermanagements zu \u00fcberwinden, implementierte Li Zheng Decoration mit Jodoo eine umfassende Mitarbeiterdatenbank und ein Zeiterfassungssystem. Diese L\u00f6sung nutzte die weit verbreitete Nutzung von Instant Messaging und Smartphones unter den Mitarbeitern und erm\u00f6glichte so einen reibungslosen und effizienten Ablauf.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Mitarbeiterinformationsmanagement<\/strong>Es wurde ein detailliertes Registrierungsformular erstellt, das wichtige Daten von Arbeitskr\u00e4ften erfasste, darunter grundlegende pers\u00f6nliche Informationen, Bankverbindungen, Berufsbezeichnungen und gescannte Kopien ihrer dreistufigen Bildungsnachweise. Diese zentrale Datenbank diente als umfassendes Arbeitskr\u00e4fte-Ressourcen-Repository und ersetzte fragmentierte Papierakten.<\/li>\n\n\n\n<li><strong>Intelligentes Anwesenheitssystem<\/strong>Die Plattform von Jodoo erm\u00f6glichte die Entwicklung eines ausgekl\u00fcgelten Zeiterfassungssystems. Mitarbeiter konnten sich pr\u00e4zise einchecken, indem sie strategisch an verschiedenen Orten (z. B. in Geb\u00e4uden, auf verschiedenen Etagen, an Baustellentoren und in Lagerhallen) platzierte QR-Codes scannten. Das System nutzte das GPS der Mobiltelefone der Mitarbeiter zur genauen Standortbestimmung. Nach dem Scannen f\u00fcllte das System automatisch relevante Felder wie Telefonnummer, T\u00e4tigkeitsart und aktuellen Standort aus und optimierte so den Check-in-Prozess. F\u00fcr nachfolgende Check-ins speicherte das System intelligent die zuvor eingegebenen Projekt- und Namensinformationen, sodass lediglich die aktuelle Eincheckzeit aktualisiert werden musste.<\/li>\n\n\n\n<li style=\"border-radius:8px\"><img decoding=\"async\" src=\"https:\/\/t9018308706.p.clickup-attachments.com\/t9018308706\/5172b9f1-a966-4b25-91a6-50a4cf206bf5\/image.png\"><\/li>\n\n\n\n<li><strong>Echtzeit\u00fcberwachung und -berichterstattung<\/strong>Ein entscheidendes Merkmal war das Echtzeit-Push-Benachrichtigungssystem. Projektmanager erhielten umgehend Benachrichtigungen \u00fcber die t\u00e4gliche Anwesenheit ihrer Mitarbeiter, wodurch physische Zeiterfassungsger\u00e4te oder manuelle \u00dcberpr\u00fcfungen \u00fcberfl\u00fcssig wurden. Diese Echtzeit-Transparenz beseitigte Probleme wie unklare Gesichtserkennung oder betr\u00fcgerisches Ein- und Ausstempeln und lieferte pr\u00e4zise und zeitnahe Anwesenheitsdaten f\u00fcr statistische Analysen und Auswertungen.<\/li>\n<\/ul>\n\n\n\n<p>Diese digitale Transformation im Bereich des Mitarbeitermanagements reduzierte die Beschaffungs- und Installationskosten im Zusammenhang mit herk\u00f6mmlichen Zeiterfassungssystemen erheblich, verbesserte die Effizienz des Projektmanagements und lieferte wertvolle Daten zur Berechnung des durchschnittlichen Produktionswerts jedes einzelnen Mitarbeiters.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"scenario-2-achieving-refined-cost-management\"><\/span>Szenario 2: Erreichen eines optimierten Kostenmanagements<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Um die Komplexit\u00e4t und Ineffizienz der Kostenkontrolle, insbesondere im Hinblick auf die \u00c4nderungsantr\u00e4ge von Partei A, anzugehen, hat Li Zheng Decoration innerhalb von Jodoo ein eigenes Kostenmanagementzentrum eingerichtet.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Optimiertes \u00c4nderungsauftragsmanagement<\/strong>Das System initiierte den \u00c4nderungsantragsprozess ab dem Zeitpunkt des Eingangs der \u00c4nderungsanweisungen f\u00fcr ein Projekt. Es erleichterte die Erstellung von Projektdokumentationen f\u00fcr \u00c4nderungsauftr\u00e4ge und verbesserte kontinuierlich die entsprechenden Formulare. Dadurch wurde ein strukturierter und nachvollziehbarer Umgang mit der gesamten Dokumentation zu \u00c4nderungsauftr\u00e4gen gew\u00e4hrleistet.<\/li>\n\n\n\n<li><strong>Interne Pr\u00fcfung und Angebotserstellung<\/strong>Das System beinhaltete einen internen Gruppenpr\u00fcfungsprozess f\u00fcr Angebote, um sicherzustellen, dass alle Kostensch\u00e4tzungen vor der Weiterbearbeitung gr\u00fcndlich gepr\u00fcft und genehmigt wurden. Dieser zentralisierte Ansatz verbesserte die Genauigkeit und Verantwortlichkeit in der Finanzplanung.<\/li>\n<\/ul>\n\n\n\n<p>Dieses optimierte Kostenmanagementsystem l\u00f6ste die Herausforderungen bei der Verwaltung von \u00c4nderungsauftr\u00e4gen und erm\u00f6glichte die Datenarchivierung in Echtzeit sowie eine transparente Fortschrittsverfolgung. Zudem erlaubte es die pr\u00e4zise Sch\u00e4tzung der Kosten externer \u00c4nderungsauftr\u00e4ge und f\u00fchrte so zu einem pr\u00e4ziseren und nachvollziehbaren Kostenmanagement \u00fcber alle Projekte hinweg.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"scenario-3-implementing-an-integrated-erp-system-for-decoration-sections\"><\/span>Szenario 3: Implementierung eines integrierten ERP-Systems f\u00fcr Dekorationsabteilungen<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Li Zheng Decoration erkannte die Notwendigkeit einer st\u00e4rker integrierten und effizienteren Lieferkette und entwickelte daher mit Jodoo ein ERP-System f\u00fcr seine Dekorationsabteilungen, um von einer fragmentierten, papierbasierten Bestandsverwaltung abzur\u00fccken.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Zentralisierte Bestandsverwaltung<\/strong>Das neue System ersetzte die manuelle, papierbasierte Erfassung von Materialeingang und -ausgang. Es erm\u00f6glichte die Echtzeit-\u00dcberwachung des Materialeingangs und -abholstatus, wodurch manuelle Berechnungen entfielen und Inkonsistenzen bei der Materialbenennung beseitigt wurden. Dieser zentralisierte Ansatz gew\u00e4hrleistete ein einheitliches Management im gesamten Unternehmen.<\/li>\n\n\n\n<li><strong>Integriertes Einkaufs- und Verkaufslager<\/strong>Durch die Nutzung des Einkaufs- und Verkaufslagersystems von Jodoo in Kombination mit den internen Managementpraktiken von Li Zheng Decoration wurde ein robustes Materialmanagementsystem etabliert. Dieses umfasste standardisierte Prozessformulare f\u00fcr die Materialbenennung, Beschaffung, Wareneingangs- und -ausgangslogistik, Umlagerungen und Retouren. Das System wurde mit der Fertigung integriert, um Echtzeit-Aktualisierungen aller Materialbewegungen zu gew\u00e4hrleisten, insbesondere der Beschaffungs- und Wareneingangsprozesse.<\/li>\n\n\n\n<li><strong>Vor-Ort-Integration mit der Instant-Communication-App<\/strong>Das System ist in eine Instant-Messaging-App f\u00fcr das Baustellenmanagement integriert. Materialverantwortliche k\u00f6nnen sich \u00fcber die App direkt auf der Baustelle einloggen, Fotos in Echtzeit aufnehmen und Waren zur Inspektion registrieren. Projektmanager und Eink\u00e4ufer k\u00f6nnen so den Wareneingang verfolgen. Das System berechnet automatisch Wert, Steuer und abzugsf\u00e4hige Steuer der aktuellen Materialk\u00e4ufe anhand der standardisierten Materialdatenbank.<\/li>\n<\/ul>\n\n\n\n<p>Dieses integrierte ERP-System lieferte Echtzeit-Einblicke in den Status der Materialbeschaffung und die tats\u00e4chlichen Ausgaben, verbesserte so die gesamte Unternehmensf\u00fchrung erheblich und stellte sicher, dass die Materialkosten kontrolliert und nachvollziehbar waren.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"conclusion-and-outlook\"><\/span>Fazit und Ausblick<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Die Zusammenarbeit von Li Zheng Decoration mit Jodoo ist ein Paradebeispiel f\u00fcr die erfolgreiche digitale Transformation in der Baubranche. Durch den Einsatz der No-Code-Plattform von Jodoo erzielte das Unternehmen signifikante Verbesserungen in der Effizienz des Online-B\u00fcros, im Datenmanagement und in der gesamten Betriebsf\u00fchrung. Die Steigerung der Online-B\u00fcroeffizienz um 901 TP\/3T und die Reduzierung des Zeitaufwands f\u00fcr Datenerfassung und -sortierung um 801 TP\/3T sind deutliche Indikatoren f\u00fcr die erzielten konkreten Vorteile.<\/p>\n\n\n\n<p>Die anf\u00e4ngliche Phase der Systemimplementierung war von einer Anpassungsphase gepr\u00e4gt, die die Bedeutung erfahrener Mitarbeiter im operativen Bereich unterstreicht, welche die Kluft zwischen Gesch\u00e4ftsanforderungen und technischen L\u00f6sungen effektiv \u00fcberbr\u00fccken k\u00f6nnen. Diese Mitarbeiter, die eine Mischung aus Produktmanagern und Entwicklern darstellen, sind entscheidend daf\u00fcr, Formulare und Prozesse an reale Szenarien anzupassen und das Vertrauen der F\u00fchrungsebene zu gewinnen.<\/p>\n\n\n\n<p>Die Erfahrungen von Li Zheng Decoration unterstreichen die weitreichenden Folgen der digitalen Transformation f\u00fcr kleine und mittlere Unternehmen. In einem Umfeld, in dem Personalfluktuation zu Arbeitsunterbrechungen f\u00fchren kann, ist ein robuster, systemorientierter Managementansatz unerl\u00e4sslich. Digitale Systeme bieten den Rahmen f\u00fcr standardisierte Arbeitsprozesse, klare Verhaltensrichtlinien und zuverl\u00e4ssige Probleml\u00f6sungsmethoden und gehen damit \u00fcber informelle F\u00fchrungsstile hinaus.<\/p>\n\n\n\n<p>Mit Blick auf die Zukunft erkennt Li Zheng Decoration den immensen wirtschaftlichen Wert der Daten, die durch seine internen Systeme generiert werden. Durch die Analyse gro\u00dfer Kostendatens\u00e4tze will das Unternehmen empirische Koeffizienten ableiten und tiefere Einblicke in seine Gesch\u00e4ftsprozesse gewinnen. Dieser datenbasierte Ansatz erm\u00f6glicht pr\u00e4zisere strategische Analysen und fundierte Entscheidungen und f\u00fchrt letztendlich zu einem umfassenden Verst\u00e4ndnis der gesch\u00e4ftlichen Zusammenh\u00e4nge.<\/p>\n\n\n\n<p>Die Erfolgsgeschichte von Li Zheng Decoration mit Jodoo ist ein \u00fcberzeugendes Beispiel daf\u00fcr, wie digitale Innovationen Bauunternehmen in die Lage versetzen k\u00f6nnen, die Effizienz zu steigern, Abl\u00e4ufe zu optimieren und eine robuste Grundlage f\u00fcr zuk\u00fcnftiges Wachstum in einem sich schnell entwickelnden Markt zu schaffen.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.jodoo.com\/request-trial\/\" rel=\"noreferrer noopener\" target=\"_blank\">Fordern Sie noch heute eine Demo an!<\/a><\/p>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Li Zheng Decoration transforms construction management with Jodoo&#8217;s no-code platform, achieving 90% efficiency gains and optimizing worker management, cost control, and supply chain processes.<\/p>","protected":false},"author":1,"featured_media":5425,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"class_list":["post-5423","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-customer"],"blocksy_meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Revolutionizing Construction Management: Li Zheng Decoration&#039;s Digital Transformation with Jodoo - Jodoo Blog<\/title>\n<meta name=\"description\" content=\"Li Zheng Decoration transforms construction management with Jodoo&#039;s no-code platform, achieving 90% efficiency gains and optimizing worker management, cost control, and supply chain processes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jodoo.com\/blog\/de-de\/kundengeschichte-lizheng\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Revolutionizing Construction Management: Li Zheng Decoration&#039;s Digital Transformation with Jodoo - Jodoo Blog\" \/>\n<meta property=\"og:description\" content=\"Li Zheng Decoration transforms construction management with Jodoo&#039;s no-code platform, achieving 90% efficiency gains and optimizing worker management, cost control, and supply chain processes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jodoo.com\/blog\/de-de\/kundengeschichte-lizheng\/\" \/>\n<meta property=\"og:site_name\" content=\"Jodoo Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/company.jodoo\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-10T13:54:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-11T08:21:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.jodoo.com\/blog\/wp-content\/uploads\/2025\/09\/lizheng-cover.png\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"464\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Jodoo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@JodooHQ\" \/>\n<meta name=\"twitter:site\" content=\"@JodooHQ\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jodoo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"8\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.jodoo.com\\\/blog\\\/customer-story-lizheng#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jodoo.com\\\/blog\\\/customer-story-lizheng\"},\"author\":{\"name\":\"Jodoo\",\"@id\":\"https:\\\/\\\/www.jodoo.com\\\/blog\\\/#\\\/schema\\\/person\\\/b958cef486b1eb00d0f82e6f0a294481\"},\"headline\":\"Revolutionizing Construction Management: Li Zheng Decoration&#8217;s Digital Transformation with Jodoo\",\"datePublished\":\"2025-09-10T13:54:12+00:00\",\"dateModified\":\"2025-09-11T08:21:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.jodoo.com\\\/blog\\\/customer-story-lizheng\"},\"wordCount\":1578,\"image\":{\"@id\":\"https:\\\/\\\/www.jodoo.com\\\/blog\\\/customer-story-lizheng#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.jodoo.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/lizheng-cover.png\",\"articleSection\":[\"Customer\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.jodoo.com\\\/blog\\\/customer-story-lizheng\",\"url\":\"https:\\\/\\\/www.jodoo.com\\\/blog\\\/customer-story-lizheng\",\"name\":\"Revolutionizing Construction Management: Li Zheng Decoration's Digital Transformation with Jodoo - Jodoo Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jodoo.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.jodoo.com\\\/blog\\\/customer-story-lizheng#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jodoo.com\\\/blog\\\/customer-story-lizheng#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.jodoo.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/lizheng-cover.png\",\"datePublished\":\"2025-09-10T13:54:12+00:00\",\"dateModified\":\"2025-09-11T08:21:58+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.jodoo.com\\\/blog\\\/#\\\/schema\\\/person\\\/b958cef486b1eb00d0f82e6f0a294481\"},\"description\":\"Li Zheng Decoration transforms construction management with Jodoo's no-code platform, achieving 90% efficiency gains and optimizing worker management, cost control, and supply chain processes.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.jodoo.com\\\/blog\\\/customer-story-lizheng#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.jodoo.com\\\/blog\\\/customer-story-lizheng\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.jodoo.com\\\/blog\\\/customer-story-lizheng#primaryimage\",\"url\":\"https:\\\/\\\/www.jodoo.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/lizheng-cover.png\",\"contentUrl\":\"https:\\\/\\\/www.jodoo.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/lizheng-cover.png\",\"width\":768,\"height\":464,\"caption\":\"lizheng cover\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.jodoo.com\\\/blog\\\/customer-story-lizheng#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u9996\u9875\",\"item\":\"https:\\\/\\\/www.jodoo.com\\\/blog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Revolutionizing Construction Management: Li Zheng Decoration&#8217;s Digital Transformation with Jodoo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.jodoo.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.jodoo.com\\\/blog\\\/\",\"name\":\"Jodoo Blog\",\"description\":\"Get the latest information about no-code development, updates, events, and other news about Jodoo.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.jodoo.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.jodoo.com\\\/blog\\\/#\\\/schema\\\/person\\\/b958cef486b1eb00d0f82e6f0a294481\",\"name\":\"Jodoo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/250e0d43b77e764b8fd961bf41dc0e46963912235f6724430a4fdb771e857168?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/250e0d43b77e764b8fd961bf41dc0e46963912235f6724430a4fdb771e857168?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/250e0d43b77e764b8fd961bf41dc0e46963912235f6724430a4fdb771e857168?s=96&d=mm&r=g\",\"caption\":\"Jodoo\"},\"sameAs\":[\"http:\\\/\\\/wp.sre.jodoodevelop.com\"],\"url\":\"https:\\\/\\\/www.jodoo.com\\\/blog\\\/de-de\\\/author\\\/wp-admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Revolutionierung des Baumanagements: Die digitale Transformation von Li Zheng Decoration mit Jodoo \u2013 Jodoo-Blog","description":"Li Zheng Decoration revolutioniert das Baumanagement mit der No-Code-Plattform von Jodoo, erzielt Effizienzgewinne nach 90% und optimiert das Personalmanagement, die Kostenkontrolle und die Lieferkettenprozesse.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jodoo.com\/blog\/de-de\/kundengeschichte-lizheng\/","og_locale":"de_DE","og_type":"article","og_title":"Revolutionizing Construction Management: Li Zheng Decoration's Digital Transformation with Jodoo - Jodoo Blog","og_description":"Li Zheng Decoration transforms construction management with Jodoo's no-code platform, achieving 90% efficiency gains and optimizing worker management, cost control, and supply chain processes.","og_url":"https:\/\/www.jodoo.com\/blog\/de-de\/kundengeschichte-lizheng\/","og_site_name":"Jodoo Blog","article_publisher":"https:\/\/www.facebook.com\/company.jodoo","article_published_time":"2025-09-10T13:54:12+00:00","article_modified_time":"2025-09-11T08:21:58+00:00","og_image":[{"width":768,"height":464,"url":"https:\/\/www.jodoo.com\/blog\/wp-content\/uploads\/2025\/09\/lizheng-cover.png","type":"image\/png"}],"author":"Jodoo","twitter_card":"summary_large_image","twitter_creator":"@JodooHQ","twitter_site":"@JodooHQ","twitter_misc":{"Verfasst von":"Jodoo","Gesch\u00e4tzte Lesezeit":"8\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jodoo.com\/blog\/customer-story-lizheng#article","isPartOf":{"@id":"https:\/\/www.jodoo.com\/blog\/customer-story-lizheng"},"author":{"name":"Jodoo","@id":"https:\/\/www.jodoo.com\/blog\/#\/schema\/person\/b958cef486b1eb00d0f82e6f0a294481"},"headline":"Revolutionizing Construction Management: Li Zheng Decoration&#8217;s Digital Transformation with Jodoo","datePublished":"2025-09-10T13:54:12+00:00","dateModified":"2025-09-11T08:21:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.jodoo.com\/blog\/customer-story-lizheng"},"wordCount":1578,"image":{"@id":"https:\/\/www.jodoo.com\/blog\/customer-story-lizheng#primaryimage"},"thumbnailUrl":"https:\/\/www.jodoo.com\/blog\/wp-content\/uploads\/2025\/09\/lizheng-cover.png","articleSection":["Customer"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.jodoo.com\/blog\/customer-story-lizheng","url":"https:\/\/www.jodoo.com\/blog\/customer-story-lizheng","name":"Revolutionierung des Baumanagements: Die digitale Transformation von Li Zheng Decoration mit Jodoo \u2013 Jodoo-Blog","isPartOf":{"@id":"https:\/\/www.jodoo.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.jodoo.com\/blog\/customer-story-lizheng#primaryimage"},"image":{"@id":"https:\/\/www.jodoo.com\/blog\/customer-story-lizheng#primaryimage"},"thumbnailUrl":"https:\/\/www.jodoo.com\/blog\/wp-content\/uploads\/2025\/09\/lizheng-cover.png","datePublished":"2025-09-10T13:54:12+00:00","dateModified":"2025-09-11T08:21:58+00:00","author":{"@id":"https:\/\/www.jodoo.com\/blog\/#\/schema\/person\/b958cef486b1eb00d0f82e6f0a294481"},"description":"Li Zheng Decoration revolutioniert das Baumanagement mit der No-Code-Plattform von Jodoo, erzielt Effizienzgewinne nach 90% und optimiert das Personalmanagement, die Kostenkontrolle und die Lieferkettenprozesse.","breadcrumb":{"@id":"https:\/\/www.jodoo.com\/blog\/customer-story-lizheng#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jodoo.com\/blog\/customer-story-lizheng"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.jodoo.com\/blog\/customer-story-lizheng#primaryimage","url":"https:\/\/www.jodoo.com\/blog\/wp-content\/uploads\/2025\/09\/lizheng-cover.png","contentUrl":"https:\/\/www.jodoo.com\/blog\/wp-content\/uploads\/2025\/09\/lizheng-cover.png","width":768,"height":464,"caption":"lizheng cover"},{"@type":"BreadcrumbList","@id":"https:\/\/www.jodoo.com\/blog\/customer-story-lizheng#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u9996\u9875","item":"https:\/\/www.jodoo.com\/blog"},{"@type":"ListItem","position":2,"name":"Revolutionizing Construction Management: Li Zheng Decoration&#8217;s Digital Transformation with Jodoo"}]},{"@type":"WebSite","@id":"https:\/\/www.jodoo.com\/blog\/#website","url":"https:\/\/www.jodoo.com\/blog\/","name":"Jodoo Blog","description":"Erhalten Sie die neuesten Informationen zu No-Code-Entwicklung, Updates, Veranstaltungen und anderen Neuigkeiten rund um Jodoo.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jodoo.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.jodoo.com\/blog\/#\/schema\/person\/b958cef486b1eb00d0f82e6f0a294481","name":"Jodoo","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/250e0d43b77e764b8fd961bf41dc0e46963912235f6724430a4fdb771e857168?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/250e0d43b77e764b8fd961bf41dc0e46963912235f6724430a4fdb771e857168?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/250e0d43b77e764b8fd961bf41dc0e46963912235f6724430a4fdb771e857168?s=96&d=mm&r=g","caption":"Jodoo"},"sameAs":["http:\/\/wp.sre.jodoodevelop.com"],"url":"https:\/\/www.jodoo.com\/blog\/de-de\/author\/wp-admin"}]}},"_links":{"self":[{"href":"https:\/\/www.jodoo.com\/blog\/de-de\/wp-json\/wp\/v2\/posts\/5423","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jodoo.com\/blog\/de-de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jodoo.com\/blog\/de-de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jodoo.com\/blog\/de-de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jodoo.com\/blog\/de-de\/wp-json\/wp\/v2\/comments?post=5423"}],"version-history":[{"count":3,"href":"https:\/\/www.jodoo.com\/blog\/de-de\/wp-json\/wp\/v2\/posts\/5423\/revisions"}],"predecessor-version":[{"id":5443,"href":"https:\/\/www.jodoo.com\/blog\/de-de\/wp-json\/wp\/v2\/posts\/5423\/revisions\/5443"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jodoo.com\/blog\/de-de\/wp-json\/wp\/v2\/media\/5425"}],"wp:attachment":[{"href":"https:\/\/www.jodoo.com\/blog\/de-de\/wp-json\/wp\/v2\/media?parent=5423"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jodoo.com\/blog\/de-de\/wp-json\/wp\/v2\/categories?post=5423"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jodoo.com\/blog\/de-de\/wp-json\/wp\/v2\/tags?post=5423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}